{"id":4418,"date":"2020-03-06T09:40:35","date_gmt":"2020-03-06T08:40:35","guid":{"rendered":"https:\/\/pergola-agava.si\/references\/"},"modified":"2021-05-07T11:53:09","modified_gmt":"2021-05-07T09:53:09","slug":"pergola-designs","status":"publish","type":"page","link":"https:\/\/pergola-agava.si\/en\/pergola-designs\/","title":{"rendered":"Pergola Designs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4418\" class=\"elementor elementor-4418 elementor-776\" data-elementor-settings=\"[]\">\n\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-element elementor-element-471de89 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"471de89\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fae8965 elementor-column elementor-col-100 elementor-top-column\" data-id=\"fae8965\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9df132d acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"9df132d\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-double_heading\">                <h2 class=\"dbl-title_wrapper\"><span class=\"dbl-title dbl-title_1\">Satisfied customers are <\/span> <span class=\"dbl-title dbl-title_2\">our greatest success<\/span>                 <\/h2>        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-element elementor-element-c5b439e elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-inner-section\" data-id=\"c5b439e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-415074e elementor-column elementor-col-100 elementor-inner-column\" data-id=\"415074e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afcad5e elementor-widget elementor-widget-text-editor\" data-id=\"afcad5e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Each Agava bioclimatic pergola has its own stories, built upon the customer\u2019s design expectations and wishes. We are confident that <strong>excellently designed terraces deserve the best pergolas<\/strong> that will enrich your outdoor living.<\/p><p style=\"text-align: left;\">Here\u2019s a number of pergola design types that can be constructed:<\/p><ul style=\"text-align: left;\"><li>Open-top pergolas;<\/li><li>Vinyl pergolas;<\/li><li>Steel pergolas;<\/li><li>Gable pergolas;<\/li><li>Sail pergolas.<\/li><\/ul><p style=\"text-align: left;\">Pergola Agava uses aluminum as a main roof material, which allows the inclusion of a number of advantages simultaneously from protection against rain to ventilation in sunny days, as well as a number of technological advancements, like barely visible drainage grooves and so on.<\/p><p style=\"text-align: left;\">There\u2019s a variety of different design models of pergola Agava with different parameters, but there are some of their implementations that are universal for all of the sizes:<\/p><ul style=\"text-align: left;\"><li>Separate location or freestanding pergola;<\/li><li>Attachment to straight house wall pergola with one or two support pillars;<\/li><li>Attachment to curved or other types of non-standard wall with one or two support pillars.<\/li><\/ul><p style=\"text-align: left;\">It\u2019s also important to mention the most prominent advantages of pergola Agava:<\/p><ul style=\"text-align: left;\"><li>High-quality materials allow for a long-term usage with little to no maintenance;<\/li><li>The structure itself is solid and secure;<\/li><li>Pergola\u2019s design is minimalistic and is capable of blending into different environments seamlessly;<\/li><li>The level of protection from various weather conditions is outstanding, you can open the roof for better climate inside the pergola, or close it for better protection.<\/li><\/ul><p style=\"text-align: left;\">Speaking of pergola designs, there\u2019s a plethora of them out there, from classic to modern, from minimalistic to lucrative, and so on. Here are some of the examples:<\/p><ul><li style=\"text-align: left;\"><strong>Estate awing style garage pergola<\/strong>. Usually attached to the garage walls, it aims to create a more dramatic look for garage outdoors. Capable of supporting vines by using support posts, too.<\/li><li style=\"text-align: left;\"><strong>Bali blinds slatted pergola<\/strong>. Using wood as a main material type, this pergola aims to give you a refreshing shade for hot summer days. The wood is often matched with the house\u2019s exterior design to make it look more natural.<\/li><li style=\"text-align: left;\"><strong>Grilling palace pergola<\/strong>. Asian design by nature, with the grill as the centerpiece of the structure. Historically such structures were designed for faithful subjects to watch over their king\/queen.<\/li><li style=\"text-align: left;\"><strong>Midcentury ranch pergola<\/strong>. A simple design that allows you to easily view your neighbours, as well as act as the window treatment for the door with a sliding mechanism. The ceiling is often made of plumbing pipe.<\/li><li style=\"text-align: left;\"><strong>Southwestern patio<\/strong>. Mostly used with Arizona-based homes in the form of a courtyard-style patio, this pergola design is used as an extension of your indoor area to allow for an easier room cooling process.<\/li><li style=\"text-align: left;\"><strong>Sunny slide-wire style pergola<\/strong>. A casual pergola style that\u2019s mostly open to allow for the refreshing breeze to come through. Due to the open-roofed nature of this design, it often includes extending fabric to make shade from the sun when you need it.<\/li><li style=\"text-align: left;\"><strong>Cleveland contemporary<\/strong>. This rectangular-shaped pergola\u2019s design has its origins in Cleveland, yet still considered to be modern. The key points of this design are simplicity and flat roof.<\/li><li style=\"text-align: left;\"><strong>Tropical parlor outdoor pergola<\/strong>. The inspiration for this particular design comes from the Victorian times, implying dark wood entrance to the parlor. Instead of the classic furniture this pergola is often decorated with blue-white tiled flooring and white and blue pillows.<\/li><li style=\"text-align: left;\"><strong>Pacific picnic wooden pergola<\/strong>. As the name suggests, this pergola\u2019s main purpose is for various picnics, with an open design and plenty of space. Picnic tables are a popular addition to this structure.<\/li><li style=\"text-align: left;\"><strong>English garden latticed pergola<\/strong>. English-inspired design with both the roof and the slats allowing for the lattice growth. Popular choice for garden parties.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-69897ba elementor-widget elementor-widget-wgl-portfolio\" data-id=\"69897ba\" data-element_type=\"widget\" data-widget_type=\"wgl-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"wgl_cpt_section\"><div class=\"wgl-portfolio\" id=\"portfolio_module_6a97db4347086\"><div class=\"portfolio__filter isotope-filter filter-center\"><a href=\"#\" data-filter=\".item\" class=\"active\">All<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/pergola-agava.si\/en\/portfolio-category\/carport-en\/\" data-filter=\".carport-en\">Carport<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/\" data-filter=\".home\">Home and Garden<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/pergola-agava.si\/en\/portfolio-category\/camping-en\/\" data-filter=\".camping-en\">Camping Pergolas<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/pergola-agava.si\/en\/portfolio-category\/restaurants\/\" data-filter=\".restaurants\">Restaurants<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/pergola-agava.si\/en\/portfolio-category\/special-projects\/\" data-filter=\".special-projects\">Special projects<span class=\"number_filter\"><\/span><\/a><\/div><div class=\"wgl-portfolio_wrapper\"><div class=\"wgl-portfolio_container container-grid row isotope portfolio_columns-3\"  style=\"margin-right:-15px; margin-left:-15px; margin-bottom:-30px;\"><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/09\/objava_02-scaled-e1663676939322-740x740.jpeg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/09\/objava_02-scaled-e1663676939322.jpeg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/09\/objava_01-scaled-e1663676849408-740x740.jpeg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/09\/objava_01-scaled-e1663676849408.jpeg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-04-at-09.49.34-e1660574431634-740x740.jpeg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-04-at-09.49.34-e1660574431634.jpeg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-ffa57a67ab8aa8fd368565d09cfd4a96-V-e1660574101709-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-ffa57a67ab8aa8fd368565d09cfd4a96-V-e1660574101709.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_obrezati-e1660574005746-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_obrezati-e1660574005746.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fbd69628fc73db6a0f1654d387a33cc0-V-e1660573759556-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fbd69628fc73db6a0f1654d387a33cc0-V-e1660573759556.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fb082826955a0dbc4bbcef959866baf6-V-e1660573684948-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fb082826955a0dbc4bbcef959866baf6-V-e1660573684948.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fa2198e62fbab24c10fdff0f07bd32f8-V-e1660573546775-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-fa2198e62fbab24c10fdff0f07bd32f8-V-e1660573546775.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-e8c0e3f3aad1ed23da46254915da088e-V-e1660573453708-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-e8c0e3f3aad1ed23da46254915da088e-V-e1660573453708.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-da4f08a0b8dbb4a6d441bbecba9b507e-V-e1660573374492-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-da4f08a0b8dbb4a6d441bbecba9b507e-V-e1660573374492.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-a82572a264f8c02b97d85fc4eb25bc59-V-e1660573252859-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-a82572a264f8c02b97d85fc4eb25bc59-V-e1660573252859.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-3945ddb2d469bf81f49808a4995f005e-V-e1660572478656-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-3945ddb2d469bf81f49808a4995f005e-V-e1660572478656.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-978ab9d7acd89b4dfe090cd5b2456a07-V-e1660572289624-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-978ab9d7acd89b4dfe090cd5b2456a07-V-e1660572289624.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-810c4bb88d34437b64d9370b6dc349bc-V-e1660572181817-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-810c4bb88d34437b64d9370b6dc349bc-V-e1660572181817.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-684a11fdcac5e35132ca1bd917a60d61-V-e1660572081536-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-684a11fdcac5e35132ca1bd917a60d61-V-e1660572081536.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-343e4301a25fca4f6b605e926a7b11d2-V-e1660571956364-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-343e4301a25fca4f6b605e926a7b11d2-V-e1660571956364.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-93ad055d9ce9bf5e59b3ca6d46e06a28-V-e1660571863665-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-93ad055d9ce9bf5e59b3ca6d46e06a28-V-e1660571863665.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-65a1ed1a6d5a1b66e37bafbf6fd20c7a-V-e1660571680351-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-65a1ed1a6d5a1b66e37bafbf6fd20c7a-V-e1660571680351.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-61fb129230297c98e4db5a80d3ceae24-V-e1660571566684-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-61fb129230297c98e4db5a80d3ceae24-V-e1660571566684.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-58cc3b08b4172bb85c58fba4bd9cf5e0-V-e1660571336924-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-58cc3b08b4172bb85c58fba4bd9cf5e0-V-e1660571336924.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-37c49982e08346d00c0830fd63928afb-V-e1660571250171-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-37c49982e08346d00c0830fd63928afb-V-e1660571250171.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-8d859165e3ba6f322b78be9829c45ad5-V-e1660571108696-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-8d859165e3ba6f322b78be9829c45ad5-V-e1660571108696.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-4ee76e22c003b813204ca5bbea066149-V-e1660570969194-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-4ee76e22c003b813204ca5bbea066149-V-e1660570969194.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-4dc86dc0ff7f2ad5ac79080f730186f3-V-e1660570801532-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-4dc86dc0ff7f2ad5ac79080f730186f3-V-e1660570801532.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-3ee8cc447af48681f6202738c0af7648-V-e1660570735692-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/IMG-3ee8cc447af48681f6202738c0af7648-V-e1660570735692.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_02-e1660569783967-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_02-e1660569783967.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_01-2-e1660569461220-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_01-2-e1660569461220.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_01-1-e1660569358236-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/AT_01-1-e1660569358236.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/At_01-e1660569163351-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/08\/At_01-e1660569163351.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/hr-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/hr.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/cro-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/cro.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/hrvaska-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/hrvaska.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/net4biz-GmbH-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/net4biz-GmbH.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/08-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/08.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/Izdelek-brez-naslova-1-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/Izdelek-brez-naslova-1.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/Izdelek-brez-naslova-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/06\/Izdelek-brez-naslova.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-2-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-2.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-1-1-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-1-1.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-1-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-1.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/Izdelek-brez-naslova.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/realizacija_02-e1653572280416-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/05\/realizacija_02-e1653572280416.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-12-e1645714604812-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-12-e1645714604812.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-11-e1645714077370-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-11-e1645714077370.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-10-e1645713588142-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-10-e1645713588142.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center gallery_type\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-9-e1645712300281-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-9-e1645712300281.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-8-e1645712058259-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-8-e1645712058259.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-7-e1645711381881-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-7-e1645711381881.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-6-e1645710979863-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-6-e1645710979863.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-5-e1645709888832-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-5-e1645709888832.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-4-e1645709455633-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-4-e1645709455633.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-3-e1645709115928-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-3-e1645709115928.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-2-e1645708644680-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-2-e1645708644680.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-1-e1645708400627-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-1-e1645708400627.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-e1645703753923-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2022\/02\/Izdelek-brez-naslova-e1645703753923.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/12\/Izdelek-brez-naslov-1-e1639122643710-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/12\/Izdelek-brez-naslov-1-e1639122643710.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/12\/Izdelek-brez-naslova-1-e1639122166772-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/12\/Izdelek-brez-naslova-1-e1639122166772.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_francija_01-e1636973070464-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_francija_01-e1636973070464.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_realizacija-e1636972180443-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_realizacija-e1636972180443.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_nemcija-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_nemcija.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_svica-1-e1636971398889-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_svica-1-e1636971398889.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_hrvaska-e1636971052632-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/soltec_hrvaska-e1636971052632.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/Izdelek-brez-naslova-1-e1636529603568-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/11\/Izdelek-brez-naslova-1-e1636529603568.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_01-e1633009193143-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_01-e1633009193143.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_04-e1633009116663-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_04-e1633009116663.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_05-e1633009049669-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_05-e1633009049669.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_06-e1633008976273-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_06-e1633008976273.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_03-e1633008854395-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_03-e1633008854395.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_02-e1633008561657-740x740.png\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/referenca_02-e1633008561657.png' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/ref_pol_01-e1632897721769-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/ref_pol_01-e1632897721769.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7862-scaled-e1632299932793-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7862-scaled-e1632299932793.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7859-scaled-e1632299804467-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7859-scaled-e1632299804467.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7929-1-scaled-e1632299692282-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7929-1-scaled-e1632299692282.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/MG_2652-scaled-e1632299113571-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/MG_2652-scaled-e1632299113571.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF8024-scaled-e1632129233669-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF8024-scaled-e1632129233669.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF8018-scaled-e1632129125946-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF8018-scaled-e1632129125946.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7860-scaled-e1632126135187-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/09\/DSF7860-scaled-e1632126135187.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/referenca_hr-e1626349256861-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/referenca_hr-e1626349256861.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/reference_01_-e1626349084118-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/reference_01_-e1626349084118.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/objava_01-e1626348609365-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/07\/objava_01-e1626348609365.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/sporar_referenca_01-scaled-e1624968758132-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/sporar_referenca_01-scaled-e1624968758132.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_01-e1624541289242-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_01-e1624541289242.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/slike_reference_avstrija-e1624540705352-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/slike_reference_avstrija-e1624540705352.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/avstrija-_01-e1623940395840-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/avstrija-_01-e1623940395840.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/FOTO-2-e1623940213607-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/FOTO-2-e1623940213607.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_11-e1623828497991-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_11-e1623828497991.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_09-scaled-e1623827871137-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_09-scaled-e1623827871137.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_08-e1623827424595-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_08-e1623827424595.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_07-scaled-e1623826582500-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_07-scaled-e1623826582500.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_06-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_06.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_05-e1623765043213-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_05-e1623765043213.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_04-e1623764897937-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_04-e1623764897937.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_03-e1623761369735-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_03-e1623761369735.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_02-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/referenca_02.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_01-1-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_01-1.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/pergola_referenca-scaled-e1622712625856-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/pergola_referenca-scaled-e1622712625856.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_03-scaled-e1622704763809-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_03-scaled-e1622704763809.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_02-e1622704533776-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/reference_02-e1622704533776.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/objava_fb_vsi_profili-e1622704409586-740x740.jpeg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/objava_fb_vsi_profili-e1622704409586.jpeg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-4 home\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper under_image h_align_center\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\"  src=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/poljska_01-e1622640364639-740x740.jpg\"  alt=\"\" \/><div class=\"overlay\"><\/div><a href='https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/06\/poljska_01-e1622640364639.jpg' class='portfolio_link swipebox'><i class='portfolio_link-icon flaticon-search-4'><\/i><\/a><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"wgl-portfolio-item_description-inner\"><div class=\"wgl-portfolio-item_meta\"><span class=\"post_cats\"><a href=https:\/\/pergola-agava.si\/en\/portfolio-category\/home\/ class=\"portfolio-category\">Home and Garden<\/a><\/span><\/div><\/div><\/div><\/div><\/article><\/div><\/div><div class=\"clear\"><\/div><div class=\"load_more_wrapper\"><div class=\"button_wrapper\"><a href=\"#\" class=\"load_more_item\"><span>More Pergola Designs<\/span><\/a><\/div><form class=\"posts_grid_ajax\"><input type='hidden' class='ajax_data' name='6a97db438e1a1_ajax_data' value='{&quot;items_load&quot;:&quot;15&quot;,&quot;name_load_more&quot;:&quot;More Pergola Designs&quot;,&quot;show_filter&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;load_more&quot;,&quot;appear_animation&quot;:null,&quot;number_of_posts&quot;:99,&quot;info_position&quot;:&quot;under_image&quot;,&quot;image_anim&quot;:null,&quot;custom_fonts_portfolio_headings_typography&quot;:&quot;custom&quot;,&quot;custom_fonts_portfolio_cats_typography&quot;:&quot;custom&quot;,&quot;custom_fonts_portfolio_cats_line_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:36,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_letter_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;load_more_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;20&quot;,&quot;right&quot;:&quot;0&quot;,&quot;bottom&quot;:&quot;0&quot;,&quot;left&quot;:&quot;0&quot;,&quot;isLinked&quot;:false},&quot;single_link_title&quot;:&quot;&quot;,&quot;custom_fonts_filter_cats_typography&quot;:&quot;custom&quot;,&quot;custom_fonts_filter_cats_font_family&quot;:&quot;Rajdhani&quot;,&quot;custom_fonts_filter_cats_font_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;taxonomies&quot;:[&quot;portfolio-category:navdihi&quot;],&quot;exclude_taxonomies&quot;:&quot;yes&quot;,&quot;show_portfolio_title&quot;:&quot;&quot;,&quot;portfolio_layout&quot;:&quot;grid&quot;,&quot;posts_per_row&quot;:&quot;3&quot;,&quot;grid_gap&quot;:&quot;30px&quot;,&quot;filter_align&quot;:&quot;center&quot;,&quot;crop_images&quot;:&quot;yes&quot;,&quot;nav_align&quot;:null,&quot;add_animation&quot;:&quot;&quot;,&quot;click_area&quot;:&quot;popup&quot;,&quot;horizontal_align&quot;:&quot;center&quot;,&quot;show_meta_categories&quot;:&quot;yes&quot;,&quot;show_content&quot;:&quot;&quot;,&quot;content_letter_count&quot;:null,&quot;add_divider&quot;:null,&quot;divider_color&quot;:&quot;#ec9123&quot;,&quot;autoplay&quot;:null,&quot;autoplay_speed&quot;:null,&quot;multiple_items&quot;:null,&quot;slides_to_scroll&quot;:null,&quot;center_mode&quot;:null,&quot;center_info&quot;:null,&quot;variable_width&quot;:null,&quot;use_pagination&quot;:null,&quot;pag_type&quot;:null,&quot;pag_offset&quot;:null,&quot;custom_pag_color&quot;:null,&quot;pag_color&quot;:null,&quot;use_prev_next&quot;:null,&quot;arrows_center_mode&quot;:null,&quot;custom_resp&quot;:null,&quot;resp_medium&quot;:null,&quot;resp_medium_slides&quot;:null,&quot;resp_tablets&quot;:null,&quot;resp_tablets_slides&quot;:null,&quot;resp_mobile&quot;:null,&quot;resp_mobile_slides&quot;:null,&quot;order_by&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;by_posts&quot;:&quot;&quot;,&quot;exclude_any&quot;:&quot;&quot;,&quot;author&quot;:&quot;&quot;,&quot;exclude_author&quot;:&quot;&quot;,&quot;filter_cats_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:12,&quot;right&quot;:30,&quot;bottom&quot;:12,&quot;left&quot;:30,&quot;isLinked&quot;:false},&quot;filter_cats_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;filter_cats_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;filter_cats_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:20,&quot;bottom&quot;:20,&quot;left&quot;:0,&quot;isLinked&quot;:false},&quot;filter_cats_margin_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;filter_cats_margin_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;custom_fonts_filter_cats_font_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_font_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_font_weight&quot;:&quot;&quot;,&quot;custom_fonts_filter_cats_text_transform&quot;:&quot;&quot;,&quot;custom_fonts_filter_cats_font_style&quot;:&quot;&quot;,&quot;custom_fonts_filter_cats_text_decoration&quot;:&quot;&quot;,&quot;custom_fonts_filter_cats_line_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_line_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_line_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_letter_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_letter_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_filter_cats_letter_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;filter_cats_color&quot;:&quot;#3b3e3e&quot;,&quot;filter_cats_background&quot;:&quot;&quot;,&quot;filter_cats_color_hover&quot;:&quot;#ffffff&quot;,&quot;filter_cats_background_hover&quot;:&quot;#ec9123&quot;,&quot;filter_cats_border_border&quot;:&quot;&quot;,&quot;filter_cats_border_width&quot;:null,&quot;filter_cats_border_width_tablet&quot;:null,&quot;filter_cats_border_width_mobile&quot;:null,&quot;filter_cats_border_color&quot;:null,&quot;filter_cats_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;filter_cats_shadow_box_shadow_type&quot;:&quot;&quot;,&quot;filter_cats_shadow_box_shadow&quot;:null,&quot;filter_cats_shadow_box_shadow_position&quot;:null,&quot;custom_fonts_portfolio_headings_font_family&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_headings_font_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_font_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_font_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_font_weight&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_headings_text_transform&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_headings_font_style&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_headings_text_decoration&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_headings_line_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_line_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_line_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_letter_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_letter_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_letter_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;h_heading_colors&quot;:&quot;&quot;,&quot;custom_headings_color&quot;:null,&quot;custom_hover_headings_color&quot;:null,&quot;custom_fonts_portfolio_cats_font_family&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_cats_font_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_font_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_font_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_font_weight&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_cats_text_transform&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_cats_font_style&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_cats_text_decoration&quot;:&quot;&quot;,&quot;custom_fonts_portfolio_cats_line_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_line_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_letter_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_cats_letter_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;h_cat_colors&quot;:&quot;&quot;,&quot;cats_color&quot;:null,&quot;cat_color_hover&quot;:null,&quot;custom_content&quot;:&quot;&quot;,&quot;custom_content_color&quot;:null,&quot;items_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;items_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;items_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;custom_desc_mask_color_background&quot;:null,&quot;custom_desc_mask_color_color&quot;:null,&quot;custom_desc_mask_color_color_stop&quot;:null,&quot;custom_desc_mask_color_color_b&quot;:null,&quot;custom_desc_mask_color_color_b_stop&quot;:null,&quot;custom_desc_mask_color_gradient_type&quot;:null,&quot;custom_desc_mask_color_gradient_angle&quot;:null,&quot;custom_desc_mask_color_gradient_position&quot;:null,&quot;custom_desc_mask_color_image&quot;:null,&quot;custom_desc_mask_color_image_tablet&quot;:null,&quot;custom_desc_mask_color_image_mobile&quot;:null,&quot;custom_desc_mask_color_position&quot;:null,&quot;custom_desc_mask_color_position_tablet&quot;:null,&quot;custom_desc_mask_color_position_mobile&quot;:null,&quot;custom_desc_mask_color_xpos&quot;:null,&quot;custom_desc_mask_color_xpos_tablet&quot;:null,&quot;custom_desc_mask_color_xpos_mobile&quot;:null,&quot;custom_desc_mask_color_ypos&quot;:null,&quot;custom_desc_mask_color_ypos_tablet&quot;:null,&quot;custom_desc_mask_color_ypos_mobile&quot;:null,&quot;custom_desc_mask_color_attachment&quot;:null,&quot;custom_desc_mask_color_repeat&quot;:null,&quot;custom_desc_mask_color_repeat_tablet&quot;:null,&quot;custom_desc_mask_color_repeat_mobile&quot;:null,&quot;custom_desc_mask_color_size&quot;:null,&quot;custom_desc_mask_color_size_tablet&quot;:null,&quot;custom_desc_mask_color_size_mobile&quot;:null,&quot;custom_desc_mask_color_bg_width&quot;:null,&quot;custom_desc_mask_color_bg_width_tablet&quot;:null,&quot;custom_desc_mask_color_bg_width_mobile&quot;:null,&quot;custom_desc_mask_color_video_link&quot;:null,&quot;custom_desc_mask_color_video_start&quot;:null,&quot;custom_desc_mask_color_video_end&quot;:null,&quot;custom_desc_mask_color_play_once&quot;:null,&quot;custom_desc_mask_color_play_on_mobile&quot;:null,&quot;custom_desc_mask_color_video_fallback&quot;:null,&quot;custom_desc_mask_color_slideshow_gallery&quot;:null,&quot;custom_desc_mask_color_slideshow_loop&quot;:null,&quot;custom_desc_mask_color_slideshow_slide_duration&quot;:null,&quot;custom_desc_mask_color_slideshow_slide_transition&quot;:null,&quot;custom_desc_mask_color_slideshow_transition_duration&quot;:null,&quot;custom_desc_mask_color_slideshow_background_size&quot;:null,&quot;custom_desc_mask_color_slideshow_background_size_tablet&quot;:null,&quot;custom_desc_mask_color_slideshow_background_size_mobile&quot;:null,&quot;custom_desc_mask_color_slideshow_background_position&quot;:null,&quot;custom_desc_mask_color_slideshow_background_position_tablet&quot;:null,&quot;custom_desc_mask_color_slideshow_background_position_mobile&quot;:null,&quot;custom_desc_mask_color_slideshow_ken_burns&quot;:null,&quot;custom_desc_mask_color_slideshow_ken_burns_zoom_direction&quot;:null,&quot;custom_image_mask_color_background&quot;:null,&quot;custom_image_mask_color_color&quot;:null,&quot;custom_image_mask_color_color_stop&quot;:null,&quot;custom_image_mask_color_color_b&quot;:null,&quot;custom_image_mask_color_color_b_stop&quot;:null,&quot;custom_image_mask_color_gradient_type&quot;:null,&quot;custom_image_mask_color_gradient_angle&quot;:null,&quot;custom_image_mask_color_gradient_position&quot;:null,&quot;custom_image_mask_color_image&quot;:null,&quot;custom_image_mask_color_image_tablet&quot;:null,&quot;custom_image_mask_color_image_mobile&quot;:null,&quot;custom_image_mask_color_position&quot;:null,&quot;custom_image_mask_color_position_tablet&quot;:null,&quot;custom_image_mask_color_position_mobile&quot;:null,&quot;custom_image_mask_color_xpos&quot;:null,&quot;custom_image_mask_color_xpos_tablet&quot;:null,&quot;custom_image_mask_color_xpos_mobile&quot;:null,&quot;custom_image_mask_color_ypos&quot;:null,&quot;custom_image_mask_color_ypos_tablet&quot;:null,&quot;custom_image_mask_color_ypos_mobile&quot;:null,&quot;custom_image_mask_color_attachment&quot;:null,&quot;custom_image_mask_color_repeat&quot;:null,&quot;custom_image_mask_color_repeat_tablet&quot;:null,&quot;custom_image_mask_color_repeat_mobile&quot;:null,&quot;custom_image_mask_color_size&quot;:null,&quot;custom_image_mask_color_size_tablet&quot;:null,&quot;custom_image_mask_color_size_mobile&quot;:null,&quot;custom_image_mask_color_bg_width&quot;:null,&quot;custom_image_mask_color_bg_width_tablet&quot;:null,&quot;custom_image_mask_color_bg_width_mobile&quot;:null,&quot;custom_image_mask_color_video_link&quot;:null,&quot;custom_image_mask_color_video_start&quot;:null,&quot;custom_image_mask_color_video_end&quot;:null,&quot;custom_image_mask_color_play_once&quot;:null,&quot;custom_image_mask_color_play_on_mobile&quot;:null,&quot;custom_image_mask_color_video_fallback&quot;:null,&quot;custom_image_mask_color_slideshow_gallery&quot;:null,&quot;custom_image_mask_color_slideshow_loop&quot;:null,&quot;custom_image_mask_color_slideshow_slide_duration&quot;:null,&quot;custom_image_mask_color_slideshow_slide_transition&quot;:null,&quot;custom_image_mask_color_slideshow_transition_duration&quot;:null,&quot;custom_image_mask_color_slideshow_background_size&quot;:null,&quot;custom_image_mask_color_slideshow_background_size_tablet&quot;:null,&quot;custom_image_mask_color_slideshow_background_size_mobile&quot;:null,&quot;custom_image_mask_color_slideshow_background_position&quot;:null,&quot;custom_image_mask_color_slideshow_background_position_tablet&quot;:null,&quot;custom_image_mask_color_slideshow_background_position_mobile&quot;:null,&quot;custom_image_mask_color_slideshow_ken_burns&quot;:null,&quot;custom_image_mask_color_slideshow_ken_burns_zoom_direction&quot;:null,&quot;sec_overlay_color&quot;:null,&quot;load_more_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:15,&quot;right&quot;:52,&quot;bottom&quot;:15,&quot;left&quot;:52,&quot;isLinked&quot;:false},&quot;load_more_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;load_more_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;load_more_margin_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;load_more_margin_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;custom_fonts_load_more_typography&quot;:&quot;&quot;,&quot;custom_fonts_load_more_font_family&quot;:null,&quot;custom_fonts_load_more_font_size&quot;:null,&quot;custom_fonts_load_more_font_size_tablet&quot;:null,&quot;custom_fonts_load_more_font_size_mobile&quot;:null,&quot;custom_fonts_load_more_font_weight&quot;:null,&quot;custom_fonts_load_more_text_transform&quot;:null,&quot;custom_fonts_load_more_font_style&quot;:null,&quot;custom_fonts_load_more_text_decoration&quot;:null,&quot;custom_fonts_load_more_line_height&quot;:null,&quot;custom_fonts_load_more_line_height_tablet&quot;:null,&quot;custom_fonts_load_more_line_height_mobile&quot;:null,&quot;custom_fonts_load_more_letter_spacing&quot;:null,&quot;custom_fonts_load_more_letter_spacing_tablet&quot;:null,&quot;custom_fonts_load_more_letter_spacing_mobile&quot;:null,&quot;load_more_color&quot;:&quot;#3b3e3e&quot;,&quot;load_more_background&quot;:&quot;&quot;,&quot;load_more_color_hover&quot;:&quot;#ffffff&quot;,&quot;load_more_background_hover&quot;:&quot;#3b3e3e&quot;,&quot;load_more_border_border&quot;:&quot;&quot;,&quot;load_more_border_width&quot;:null,&quot;load_more_border_width_tablet&quot;:null,&quot;load_more_border_width_mobile&quot;:null,&quot;load_more_border_color&quot;:null,&quot;load_more_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;load_more_shadow_box_shadow_type&quot;:&quot;&quot;,&quot;load_more_shadow_box_shadow&quot;:null,&quot;load_more_shadow_box_shadow_position&quot;:null,&quot;_title&quot;:&quot;&quot;,&quot;_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_margin_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_margin_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_z_index&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;_css_classes&quot;:&quot;&quot;,&quot;_animation&quot;:&quot;&quot;,&quot;_animation_tablet&quot;:&quot;&quot;,&quot;_animation_mobile&quot;:&quot;&quot;,&quot;animation_duration&quot;:null,&quot;_animation_delay&quot;:null,&quot;_background_background&quot;:&quot;&quot;,&quot;_background_color&quot;:null,&quot;_background_color_stop&quot;:null,&quot;_background_color_b&quot;:null,&quot;_background_color_b_stop&quot;:null,&quot;_background_gradient_type&quot;:null,&quot;_background_gradient_angle&quot;:null,&quot;_background_gradient_position&quot;:null,&quot;_background_image&quot;:null,&quot;_background_image_tablet&quot;:null,&quot;_background_image_mobile&quot;:null,&quot;_background_position&quot;:null,&quot;_background_position_tablet&quot;:null,&quot;_background_position_mobile&quot;:null,&quot;_background_xpos&quot;:null,&quot;_background_xpos_tablet&quot;:null,&quot;_background_xpos_mobile&quot;:null,&quot;_background_ypos&quot;:null,&quot;_background_ypos_tablet&quot;:null,&quot;_background_ypos_mobile&quot;:null,&quot;_background_attachment&quot;:null,&quot;_background_repeat&quot;:null,&quot;_background_repeat_tablet&quot;:null,&quot;_background_repeat_mobile&quot;:null,&quot;_background_size&quot;:null,&quot;_background_size_tablet&quot;:null,&quot;_background_size_mobile&quot;:null,&quot;_background_bg_width&quot;:null,&quot;_background_bg_width_tablet&quot;:null,&quot;_background_bg_width_mobile&quot;:null,&quot;_background_video_link&quot;:null,&quot;_background_video_start&quot;:null,&quot;_background_video_end&quot;:null,&quot;_background_play_once&quot;:null,&quot;_background_play_on_mobile&quot;:null,&quot;_background_video_fallback&quot;:null,&quot;_background_slideshow_gallery&quot;:null,&quot;_background_slideshow_loop&quot;:null,&quot;_background_slideshow_slide_duration&quot;:null,&quot;_background_slideshow_slide_transition&quot;:null,&quot;_background_slideshow_transition_duration&quot;:null,&quot;_background_slideshow_background_size&quot;:null,&quot;_background_slideshow_background_size_tablet&quot;:null,&quot;_background_slideshow_background_size_mobile&quot;:null,&quot;_background_slideshow_background_position&quot;:null,&quot;_background_slideshow_background_position_tablet&quot;:null,&quot;_background_slideshow_background_position_mobile&quot;:null,&quot;_background_slideshow_ken_burns&quot;:null,&quot;_background_slideshow_ken_burns_zoom_direction&quot;:null,&quot;_background_hover_background&quot;:&quot;&quot;,&quot;_background_hover_color&quot;:null,&quot;_background_hover_color_stop&quot;:null,&quot;_background_hover_color_b&quot;:null,&quot;_background_hover_color_b_stop&quot;:null,&quot;_background_hover_gradient_type&quot;:null,&quot;_background_hover_gradient_angle&quot;:null,&quot;_background_hover_gradient_position&quot;:null,&quot;_background_hover_image&quot;:null,&quot;_background_hover_image_tablet&quot;:null,&quot;_background_hover_image_mobile&quot;:null,&quot;_background_hover_position&quot;:null,&quot;_background_hover_position_tablet&quot;:null,&quot;_background_hover_position_mobile&quot;:null,&quot;_background_hover_xpos&quot;:null,&quot;_background_hover_xpos_tablet&quot;:null,&quot;_background_hover_xpos_mobile&quot;:null,&quot;_background_hover_ypos&quot;:null,&quot;_background_hover_ypos_tablet&quot;:null,&quot;_background_hover_ypos_mobile&quot;:null,&quot;_background_hover_attachment&quot;:null,&quot;_background_hover_repeat&quot;:null,&quot;_background_hover_repeat_tablet&quot;:null,&quot;_background_hover_repeat_mobile&quot;:null,&quot;_background_hover_size&quot;:null,&quot;_background_hover_size_tablet&quot;:null,&quot;_background_hover_size_mobile&quot;:null,&quot;_background_hover_bg_width&quot;:null,&quot;_background_hover_bg_width_tablet&quot;:null,&quot;_background_hover_bg_width_mobile&quot;:null,&quot;_background_hover_video_link&quot;:null,&quot;_background_hover_video_start&quot;:null,&quot;_background_hover_video_end&quot;:null,&quot;_background_hover_play_once&quot;:null,&quot;_background_hover_play_on_mobile&quot;:null,&quot;_background_hover_video_fallback&quot;:null,&quot;_background_hover_slideshow_gallery&quot;:null,&quot;_background_hover_slideshow_loop&quot;:null,&quot;_background_hover_slideshow_slide_duration&quot;:null,&quot;_background_hover_slideshow_slide_transition&quot;:null,&quot;_background_hover_slideshow_transition_duration&quot;:null,&quot;_background_hover_slideshow_background_size&quot;:null,&quot;_background_hover_slideshow_background_size_tablet&quot;:null,&quot;_background_hover_slideshow_background_size_mobile&quot;:null,&quot;_background_hover_slideshow_background_position&quot;:null,&quot;_background_hover_slideshow_background_position_tablet&quot;:null,&quot;_background_hover_slideshow_background_position_mobile&quot;:null,&quot;_background_hover_slideshow_ken_burns&quot;:null,&quot;_background_hover_slideshow_ken_burns_zoom_direction&quot;:null,&quot;_background_hover_transition&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_border_border&quot;:&quot;&quot;,&quot;_border_width&quot;:null,&quot;_border_width_tablet&quot;:null,&quot;_border_width_mobile&quot;:null,&quot;_border_color&quot;:null,&quot;_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_box_shadow_box_shadow_type&quot;:&quot;&quot;,&quot;_box_shadow_box_shadow&quot;:null,&quot;_box_shadow_box_shadow_position&quot;:null,&quot;_border_hover_border&quot;:&quot;&quot;,&quot;_border_hover_width&quot;:null,&quot;_border_hover_width_tablet&quot;:null,&quot;_border_hover_width_mobile&quot;:null,&quot;_border_hover_color&quot;:null,&quot;_border_radius_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_border_radius_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_border_radius_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;_box_shadow_hover_box_shadow_type&quot;:&quot;&quot;,&quot;_box_shadow_hover_box_shadow&quot;:null,&quot;_box_shadow_hover_box_shadow_position&quot;:null,&quot;_border_hover_transition&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_element_width&quot;:&quot;&quot;,&quot;_element_width_tablet&quot;:&quot;&quot;,&quot;_element_width_mobile&quot;:&quot;&quot;,&quot;_element_custom_width&quot;:null,&quot;_element_custom_width_tablet&quot;:null,&quot;_element_custom_width_mobile&quot;:null,&quot;_element_vertical_align&quot;:null,&quot;_element_vertical_align_tablet&quot;:null,&quot;_element_vertical_align_mobile&quot;:null,&quot;_position&quot;:&quot;&quot;,&quot;_offset_orientation_h&quot;:null,&quot;_offset_x&quot;:null,&quot;_offset_x_tablet&quot;:null,&quot;_offset_x_mobile&quot;:null,&quot;_offset_x_end&quot;:null,&quot;_offset_x_end_tablet&quot;:null,&quot;_offset_x_end_mobile&quot;:null,&quot;_offset_orientation_v&quot;:null,&quot;_offset_y&quot;:null,&quot;_offset_y_tablet&quot;:null,&quot;_offset_y_mobile&quot;:null,&quot;_offset_y_end&quot;:null,&quot;_offset_y_end_tablet&quot;:null,&quot;_offset_y_end_mobile&quot;:null,&quot;hide_desktop&quot;:&quot;&quot;,&quot;hide_tablet&quot;:&quot;&quot;,&quot;hide_mobile&quot;:&quot;&quot;,&quot;post_count&quot;:99,&quot;found_posts&quot;:321,&quot;query_args&quot;:{&quot;post_status&quot;:&quot;publish&quot;,&quot;posts_per_page&quot;:99,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;tax_query&quot;:{&quot;relation&quot;:&quot;AND&quot;,&quot;0&quot;:{&quot;field&quot;:&quot;slug&quot;,&quot;taxonomy&quot;:&quot;portfolio-category&quot;,&quot;terms&quot;:[&quot;inspirations&quot;],&quot;operator&quot;:&quot;NOT IN&quot;}},&quot;paged&quot;:1,&quot;post_type&quot;:&quot;portfolio&quot;}}' \/><\/form><\/div><\/div><\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff6ce50 elementor-widget elementor-widget-spacer\" data-id=\"ff6ce50\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Satisfied customers are our greatest success Each Agava bioclimatic pergola has its own stories, built upon the customer\u2019s design expectations and wishes. We are confident that excellently designed terraces deserve the best pergolas that will enrich your outdoor living. Here\u2019s a number of pergola design types that can be constructed: Open-top pergolas; Vinyl pergolas; Steel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The modern pergola designs. Pergola design ideas. Small pergola designs<\/title>\n<meta name=\"description\" content=\"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pergola-agava.si\/en\/pergola-designs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The modern pergola designs. Pergola design ideas. Small pergola designs\" \/>\n<meta property=\"og:description\" content=\"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pergola-agava.si\/en\/pergola-designs\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioklimatska pergola Agava\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T09:53:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/05\/prva_objava-e1620307350348-740x740.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"24 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pergola-agava.si\/en\/pergola-designs\/\",\"url\":\"https:\/\/pergola-agava.si\/en\/pergola-designs\/\",\"name\":\"The modern pergola designs. Pergola design ideas. Small pergola designs\",\"isPartOf\":{\"@id\":\"https:\/\/pergola-agava.si\/en\/#website\"},\"datePublished\":\"2020-03-06T08:40:35+00:00\",\"dateModified\":\"2021-05-07T09:53:09+00:00\",\"description\":\"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.\",\"breadcrumb\":{\"@id\":\"https:\/\/pergola-agava.si\/en\/pergola-designs\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pergola-agava.si\/en\/pergola-designs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pergola-agava.si\/en\/pergola-designs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pergola-agava.si\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pergola Designs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pergola-agava.si\/en\/#website\",\"url\":\"https:\/\/pergola-agava.si\/en\/\",\"name\":\"Bioklimatska pergola Agava\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pergola-agava.si\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The modern pergola designs. Pergola design ideas. Small pergola designs","description":"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pergola-agava.si\/en\/pergola-designs\/","og_locale":"en_US","og_type":"article","og_title":"The modern pergola designs. Pergola design ideas. Small pergola designs","og_description":"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.","og_url":"https:\/\/pergola-agava.si\/en\/pergola-designs\/","og_site_name":"Bioklimatska pergola Agava","article_modified_time":"2021-05-07T09:53:09+00:00","og_image":[{"url":"https:\/\/pergola-agava.si\/wp-content\/uploads\/2021\/05\/prva_objava-e1620307350348-740x740.jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"24 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pergola-agava.si\/en\/pergola-designs\/","url":"https:\/\/pergola-agava.si\/en\/pergola-designs\/","name":"The modern pergola designs. Pergola design ideas. Small pergola designs","isPartOf":{"@id":"https:\/\/pergola-agava.si\/en\/#website"},"datePublished":"2020-03-06T08:40:35+00:00","dateModified":"2021-05-07T09:53:09+00:00","description":"The modern pergola designs and ideas that are implemented with the aluminium Agava pergola. Pergola Agava ideas for outdoor rest near home, in the garden, restaurant and in the other places.","breadcrumb":{"@id":"https:\/\/pergola-agava.si\/en\/pergola-designs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pergola-agava.si\/en\/pergola-designs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pergola-agava.si\/en\/pergola-designs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pergola-agava.si\/en\/"},{"@type":"ListItem","position":2,"name":"Pergola Designs"}]},{"@type":"WebSite","@id":"https:\/\/pergola-agava.si\/en\/#website","url":"https:\/\/pergola-agava.si\/en\/","name":"Bioklimatska pergola Agava","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pergola-agava.si\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/pages\/4418"}],"collection":[{"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/comments?post=4418"}],"version-history":[{"count":13,"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/pages\/4418\/revisions"}],"predecessor-version":[{"id":15568,"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/pages\/4418\/revisions\/15568"}],"wp:attachment":[{"href":"https:\/\/pergola-agava.si\/en\/wp-json\/wp\/v2\/media?parent=4418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}